{"id":30,"count":4,"description":"","link":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/","name":"Unternehmensgr\u00fcndung K\u00e4rnten","slug":"unternehmensgruendung-kaernten","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/\" \/>\n<meta property=\"og:site_name\" content=\"Initiative Gr\u00fcndergarage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/tag\\\/unternehmensgruendung-kaernten\\\/\",\"url\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/tag\\\/unternehmensgruendung-kaernten\\\/\",\"name\":\"Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/tag\\\/unternehmensgruendung-kaernten\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/tag\\\/unternehmensgruendung-kaernten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unternehmensgr\u00fcndung K\u00e4rnten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/#website\",\"url\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/\",\"name\":\"Initiative Gr\u00fcndergarage\",\"description\":\"FH K\u00e4rnten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage","og_url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/","og_site_name":"Initiative Gr\u00fcndergarage","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/","url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/","name":"Unternehmensgr\u00fcndung K\u00e4rnten Archive - Initiative Gr\u00fcndergarage","isPartOf":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/#website"},"breadcrumb":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/tag\/unternehmensgruendung-kaernten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/"},{"@type":"ListItem","position":2,"name":"Unternehmensgr\u00fcndung K\u00e4rnten"}]},{"@type":"WebSite","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/#website","url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/","name":"Initiative Gr\u00fcndergarage","description":"FH K\u00e4rnten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/tags\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/posts?tags=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}