{"id":509,"date":"2020-02-20T13:59:41","date_gmt":"2020-02-20T12:59:41","guid":{"rendered":"http:\/\/blog.fh-kaernten.at\/gruendergarage\/?p=509"},"modified":"2021-05-07T08:49:30","modified_gmt":"2021-05-07T06:49:30","slug":"scientrepreneur-2","status":"publish","type":"post","link":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/","title":{"rendered":"SCIENTREPRENEUR 2020"},"content":{"rendered":"\n<p><strong>Zielsetzung<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Auseinandersetzung mit dem Unternehmertum<\/li><li>Awareness fu\u0308r Business-Opportunities Forschende &amp; Lehrende als Scouts und Mentoren fu\u0308r Innovation und Gru\u0308ndung<\/li><li>Vermittlung von Basis-Wissen zur Unternehmensgru\u0308ndung<\/li><\/ul>\n\n\n\n<p><strong>Zielgruppe<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Forscher und Laboringenieure<\/li><li>Lehrende<\/li><li>Interessierte &amp; Unterstu\u0308tzer fu\u0308r Gru\u0308ndung<\/li><\/ul>\n\n\n\n<p><strong>Kosten und Anmeldung<\/strong><\/p>\n\n\n\n<p>Im Rahmen des Pilotprojekts kostenfrei! Reise- und Verpflegungskosten sind durch die Teilnehmer bzw. deren Organisationen zu tragen.<br><\/p>\n\n\n\n<p><strong>Termin:<\/strong> M\u00e4rz &#8211; Mai 2020; die genauen Termine zu den jeweiligen Modulen finden Sie im Anhang. <br><strong>Anmeldung: <\/strong>bitte per E-Mail an <a href=\"mailto:scientrepreneur@fh-kaernten.at\">scientrepreneur@fh-kaernten.at<\/a><br>Begrenzte Teilnehmerzahl! <strong>Anmeldeschluss: 11.03.2020<\/strong><\/p>\n\n\n<p>N\u00e4here Details entnehmen Sie bitte dem <a href=\"http:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/Flyer_Scientrepreneur-2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Flyer Scientrepreneur 2020<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Basiswissen fu\u0308r Gru\u0308nder*innen<br \/>\nM\u00e4rz \u2013 Mai 2020<br \/>\nFH K\u00e4rnten, Campus Villach, Innovationswerkstatt<\/p>\n","protected":false},"author":171,"featured_media":548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[31,32,30,34,33],"class_list":["post-509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weiterbildung-workshops","tag-basiswissen-gruendung-kaernten","tag-start-up-kaernten","tag-unternehmensgruendung-kaernten","tag-weiterbildungsangebot-unternehmensgruendung-kaernten","tag-workshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage\" \/>\n<meta property=\"og:description\" content=\"Basiswissen fu\u0308r Gru\u0308nder*innen M\u00e4rz \u2013 Mai 2020 FH K\u00e4rnten, Campus Villach, Innovationswerkstatt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Initiative Gr\u00fcndergarage\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-20T12:59:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T06:49:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SCIENTREPRENEUR 2020\",\"datePublished\":\"2020-02-20T12:59:41+00:00\",\"dateModified\":\"2021-05-07T06:49:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/\"},\"wordCount\":98,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/files\\\/2020\\\/02\\\/gruendergarage-beitragsbild2-1.jpg\",\"keywords\":[\"Basiswissen Gr\u00fcndung K\u00e4rnten\",\"Start Up K\u00e4rnten\",\"Unternehmensgr\u00fcndung K\u00e4rnten\",\"Weiterbildungsangebot Unternehmensgr\u00fcndung K\u00e4rnten\",\"Workshop\"],\"articleSection\":[\"Weiterbildung\\\/Workshops\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/\",\"url\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/\",\"name\":\"SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/files\\\/2020\\\/02\\\/gruendergarage-beitragsbild2-1.jpg\",\"datePublished\":\"2020-02-20T12:59:41+00:00\",\"dateModified\":\"2021-05-07T06:49:30+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/files\\\/2020\\\/02\\\/gruendergarage-beitragsbild2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/files\\\/2020\\\/02\\\/gruendergarage-beitragsbild2-1.jpg\",\"width\":517,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/scientrepreneur-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCIENTREPRENEUR 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/#website\",\"url\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/\",\"name\":\"Initiative Gr\u00fcndergarage\",\"description\":\"FH K\u00e4rnten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.fh-kaernten.at\\\/gruendergarage\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/","og_locale":"de_DE","og_type":"article","og_title":"SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage","og_description":"Basiswissen fu\u0308r Gru\u0308nder*innen M\u00e4rz \u2013 Mai 2020 FH K\u00e4rnten, Campus Villach, Innovationswerkstatt","og_url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/","og_site_name":"Initiative Gr\u00fcndergarage","article_published_time":"2020-02-20T12:59:41+00:00","article_modified_time":"2021-05-07T06:49:30+00:00","og_image":[{"width":517,"height":489,"url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#article","isPartOf":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/"},"author":{"name":"","@id":""},"headline":"SCIENTREPRENEUR 2020","datePublished":"2020-02-20T12:59:41+00:00","dateModified":"2021-05-07T06:49:30+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/"},"wordCount":98,"commentCount":0,"image":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg","keywords":["Basiswissen Gr\u00fcndung K\u00e4rnten","Start Up K\u00e4rnten","Unternehmensgr\u00fcndung K\u00e4rnten","Weiterbildungsangebot Unternehmensgr\u00fcndung K\u00e4rnten","Workshop"],"articleSection":["Weiterbildung\/Workshops"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/","url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/","name":"SCIENTREPRENEUR 2020 - Initiative Gr\u00fcndergarage","isPartOf":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#primaryimage"},"image":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg","datePublished":"2020-02-20T12:59:41+00:00","dateModified":"2021-05-07T06:49:30+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#primaryimage","url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg","contentUrl":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/files\/2020\/02\/gruendergarage-beitragsbild2-1.jpg","width":517,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/scientrepreneur-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/"},{"@type":"ListItem","position":2,"name":"SCIENTREPRENEUR 2020"}]},{"@type":"WebSite","@id":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/#website","url":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/","name":"Initiative Gr\u00fcndergarage","description":"FH K\u00e4rnten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/posts\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":0,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/media\/548"}],"wp:attachment":[{"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.fh-kaernten.at\/gruendergarage\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}